{"id":5411,"date":"2018-12-29T18:39:31","date_gmt":"2018-12-29T18:39:31","guid":{"rendered":"https:\/\/manoli.ca\/?p=5411"},"modified":"2019-09-10T22:24:47","modified_gmt":"2019-09-10T22:24:47","slug":"metoo-les-femmes-veulent-se-defendre","status":"publish","type":"post","link":"https:\/\/manoli.ca\/fr\/metoo-les-femmes-veulent-se-defendre\/","title":{"rendered":"#MeToo : les femmes veulent se d\u00e9fendre &#8211; July 2018"},"content":{"rendered":"<p><strong>This story was originally published in <a href=\"https:\/\/www.tvanouvelles.ca\/2018\/07\/02\/metoo--les-femmes-veulent-se-defendre\">TVA Nouvelles (Video)<\/a><\/strong><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-5412\" src=\"https:\/\/manoli.ca\/wp-content\/uploads\/2018\/12\/MeToo-les-femmes-veulent-se-d\u00e9fendre-2.jpg\" alt=\"\" width=\"900\" height=\"506\" srcset=\"https:\/\/manoli.ca\/wp-content\/uploads\/2018\/12\/MeToo-les-femmes-veulent-se-d\u00e9fendre-2.jpg 900w, https:\/\/manoli.ca\/wp-content\/uploads\/2018\/12\/MeToo-les-femmes-veulent-se-d\u00e9fendre-2-300x169.jpg 300w, https:\/\/manoli.ca\/wp-content\/uploads\/2018\/12\/MeToo-les-femmes-veulent-se-d\u00e9fendre-2-768x432.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>Les femmes sont de plus en plus nombreuses \u00e0 s\u2019inscrire \u00e0 des cours d\u2019autod\u00e9fense \u00e0 Montr\u00e9al pour apprendre \u00e0 se prot\u00e9ger contre les agressions, moins d\u2019un an apr\u00e8s le mouvement #meToo.<\/p>\n<p>\u00ab Depuis le d\u00e9but de l\u2019ann\u00e9e, j\u2019ai doubl\u00e9, voire tripl\u00e9 le nombre de cours que je donne aux femmes. L\u2019augmentation est flagrante \u00bb, dit George Manoli, qui dirige une \u00e9cole d\u2019autod\u00e9fense et de karat\u00e9 \u00e0 Montr\u00e9al. Il dit avoir form\u00e9 pr\u00e8s de 200 femmes en 2018.<\/p>\n<p>Plusieurs autres \u00e9coles ont affirm\u00e9 au&nbsp;Journal&nbsp;avoir observ\u00e9 ces derniers mois une hausse du nombre d\u2019inscriptions aux cours d\u2019autod\u00e9fense f\u00e9minine.<\/p>\n<p>M.&nbsp;Manoli estime que le mouvement #meToo et les discussions sur les agressions subies par les femmes qui a suivi ont pouss\u00e9 beaucoup d\u2019entre elles \u00e0 vouloir mieux se d\u00e9fendre.<\/p>\n<h2>Menac\u00e9e<\/h2>\n<p>\u00ab Je me suis d\u00e9j\u00e0 fait menacer dans la rue par un homme qui avait un couteau, raconte Sarah Kamal, une \u00e9crivaine de 41 ans qui a r\u00e9cemment assist\u00e9 au cours de M.&nbsp;Manoli. Je l\u2019ai pouss\u00e9, et il est parti en courant, mais je me suis toujours demand\u00e9 ce que j\u2019aurais fait s\u2019il m\u2019avait vraiment attaqu\u00e9e. \u00bb<\/p>\n<p>Pour mieux pr\u00e9parer ses \u00e9l\u00e8ves \u00e0 ces situations, George Manoli simule des agressions lors de ses cours, de la fa\u00e7on la plus r\u00e9aliste possible.<\/p>\n<p>\u00ab Je veux qu\u2019elles puissent mettre en pratique ce qu\u2019elles apprennent, dit-il. C\u2019est pour \u00e7a que je les am\u00e8ne dehors pour certains cours ou que je leur dis de porter des talons. On fait aussi des simulations contre un mur, parce que la plupart des agressions ne se passent pas \u00e0 une distance de deux m\u00e8tres, mais au corps \u00e0 corps. \u00bb<\/p>\n<p>M.&nbsp;Manoli travaille aussi la d\u00e9fense au sol en montrant aux femmes comment utiliser leurs jambes pour repousser leur adversaire.<\/p>\n<h2>Frapper fort<\/h2>\n<p>En un cours d\u2019une heure et demie, les femmes peuvent \u00eatre confront\u00e9es \u00e0 six situations. L\u2019\u00e9quipement matelass\u00e9 de l\u2019instructeur leur permet de lib\u00e9rer leur force sans retenue.<\/p>\n<p>\u00ab C\u2019est tr\u00e8s important, \u00e7a nous permet de frapper fort et de comprendre qu\u2019il n\u2019y a pas que les gar\u00e7ons qui ont le droit de se d\u00e9fendre physiquement \u00bb, dit Sarah Kamal.<\/p>\n<p>\u00ab La semaine derni\u00e8re, \u00e0 la fin du cours, une \u00e9l\u00e8ve m\u2019a f\u00e9licit\u00e9e en me disant que je faisais vraiment peur quand je frappais, raconte M\u00e9lanie Tabet, une autre \u00e9l\u00e8ve de M.&nbsp;Manoli. J\u2019\u00e9tais \u00e9tonn\u00e9e, je ne connaissais pas cet aspect de ma personnalit\u00e9. Moi, j\u2019ai plut\u00f4t \u00e9t\u00e9 habitu\u00e9e \u00e0 \u00e9viter les conflits. \u00bb<\/p>\n<p>Beatriz Mu\u00f1oz, qui dirige le programme d\u2019autod\u00e9fense f\u00e9minine ACTION, au sein du Centre de pr\u00e9vention des agressions de Montr\u00e9al, apprend aux participantes \u00e0 se r\u00e9approprier leur corps et \u00e0 se lib\u00e9rer du clich\u00e9 de la femme fragile.<\/p>\n<p>\u00ab On leur dit par exemple de pousser des cris graves et puissants, l\u2019inverse de ce que font les femmes dans les films, explique-t-elle. De mani\u00e8re g\u00e9n\u00e9rale, l\u2019autod\u00e9fense va \u00e0 l\u2019encontre de l\u2019\u00e9ducation que l\u2019on a re\u00e7ue en tant que femme, o\u00f9 l\u2019on nous a appris \u00e0 \u00eatre gentilles et \u00e0 ne pas&nbsp;g\u00eaner&nbsp;\u00bb.<\/p>\n<p>Le programme qu\u2019elle anime a \u00e9t\u00e9 pens\u00e9 par et pour des femmes.<\/p>\n<p>\u00ab \u00c7a peut mettre en confiance celles qui ont de l\u2019appr\u00e9hension \u00e0 faire de l\u2019autod\u00e9fense ou \u00e0 se battre. Elles savent que nous les comprenons \u00bb, dit-elle.<\/p>\n<h2>Les victimes affrontent leurs peurs<\/h2>\n<p>Des instructeurs d\u2019autod\u00e9fense font revivre \u00e0 des victimes les agressions qu\u2019elles ont subies pour les aider \u00e0 surmonter leur traumatisme.<\/p>\n<p>\u00ab Quand les gens se font agresser, ils gardent en t\u00eate une sorte de vid\u00e9o de ce qu\u2019il s\u2019est pass\u00e9, explique l\u2019instructeur d\u2019autod\u00e9fense George Manoli. On ne peut pas effacer ce vid\u00e9o, mais on va en cr\u00e9er un nouveau, plus positif, en parall\u00e8le. \u00bb<\/p>\n<p>Ce sp\u00e9cialiste, qui dirige \u00e0 Montr\u00e9al son \u00e9cole d\u2019autod\u00e9fense et de karat\u00e9, re\u00e7oit plusieurs victimes d\u2019agression, r\u00e9f\u00e9r\u00e9es notamment, par la Direction de l\u2019indemnisation des victimes d\u2019actes criminels (IVAC).<\/p>\n<p>\u00ab J\u2019ai des personnes qui ont v\u00e9cu de l\u2019inceste, des violences conjugales et des agressions sexuelles, explique-t-il. Souvent, elles n\u2019osent plus sortir dehors. \u00bb<\/p>\n<p>George Manoli indique qu\u2019il ne se substitue pas aux psychologues, mais agit en compl\u00e9mentarit\u00e9, en proposant une approche personnalis\u00e9e.<\/p>\n<h2>Le bruit du r\u00e2teau<\/h2>\n<p>Il cite une femme d\u2019une cinquantaine d\u2019ann\u00e9es ayant \u00e9t\u00e9 agress\u00e9e sexuellement par son p\u00e8re lorsqu\u2019elle \u00e9tait enfant.<\/p>\n<p>\u00ab Quand elle \u00e9tait jeune, elle habitait sur une ferme, et son papa utilisait des outils comme des r\u00e2teaux ou des pelles pour la menacer. Le bruit la figeait. Ce qui l\u2019a \u00e9norm\u00e9ment aid\u00e9e, c\u2019est de faire des simulations d\u2019agression les yeux band\u00e9s. Elle revivait la sc\u00e8ne, mais dans sa t\u00eate, en se concentrant sur le son. \u00bb<\/p>\n<p>Thierry Cimkauskas, un professeur de krav maga \u2013 une technique d\u2019autod\u00e9fense de l\u2019arm\u00e9e isra\u00e9lienne \u2013 qui travaille, lui aussi, avec des victimes, insiste sur l\u2019importance de la pr\u00e9paration mentale.<\/p>\n<p>\u00ab On les fait travailler sur des techniques qui demandent \u00e0 ce qu\u2019elles soient concentr\u00e9es 100&nbsp;% sur leurs mouvements, de fa\u00e7on \u00e0 se d\u00e9connecter de leurs probl\u00e8mes \u00bb, affirme-t-il.<\/p>\n<h2>Reprendre confiance<\/h2>\n<p>Il pr\u00e9cise que l\u2019effet de ces s\u00e9ances peut se faire sentir tr\u00e8s rapidement.<\/p>\n<p>\u00ab La semaine derni\u00e8re, une \u00e9l\u00e8ve qui avait \u00e9t\u00e9 agress\u00e9e par un homme m\u2019a envoy\u00e9 un message pour me dire qu\u2019elle revivait et qu\u2019elle sortait \u00e0 nouveau de chez elle, raconte l\u2019instructeur. Elle n\u2019avait fait qu\u2019une dizaine de cours, mais \u00e7a a suffi \u00e0 lui redonner confiance. \u00bb<\/p>\n<h3>Related Images:<\/h3>","protected":false},"excerpt":{"rendered":"<p>This story was originally published in TVA Nouvelles (Video) Les femmes sont de plus en plus nombreuses \u00e0 s\u2019inscrire \u00e0 des cours d\u2019autod\u00e9fense \u00e0 Montr\u00e9al pour apprendre \u00e0 se prot\u00e9ger contre les agressions, moins d\u2019un an apr\u00e8s le mouvement #meToo. \u00ab Depuis le d\u00e9but de l\u2019ann\u00e9e, j\u2019ai doubl\u00e9, voire tripl\u00e9 le nombre de cours que &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[85,16],"tags":[],"class_list":["post-5411","post","type-post","status-publish","format-standard","hentry","category-articles","category-assault-prevention"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#MeToo : les femmes veulent se d\u00e9fendre - July 2018 - George Manoli Inc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#MeToo : les femmes veulent se d\u00e9fendre - July 2018 - George Manoli Inc\" \/>\n<meta property=\"og:description\" content=\"This story was originally published in TVA Nouvelles (Video) Les femmes sont de plus en plus nombreuses \u00e0 s\u2019inscrire \u00e0 des cours d\u2019autod\u00e9fense \u00e0 Montr\u00e9al pour apprendre \u00e0 se prot\u00e9ger contre les agressions, moins d\u2019un an apr\u00e8s le mouvement #meToo. \u00ab Depuis le d\u00e9but de l\u2019ann\u00e9e, j\u2019ai doubl\u00e9, voire tripl\u00e9 le nombre de cours que ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/\" \/>\n<meta property=\"og:site_name\" content=\"George Manoli Inc\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-29T18:39:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-10T22:24:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/manoli.ca\/wp-content\/uploads\/2015\/12\/Red-Barn-Logo-250-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"George Manoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tokondojo\" \/>\n<meta name=\"twitter:site\" content=\"@tokondojo\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Manoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/manoli.ca\\\/metoo-les-femmes-veulent-se-defendre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manoli.ca\\\/metoo-les-femmes-veulent-se-defendre\\\/\"},\"author\":{\"name\":\"George Manoli\",\"@id\":\"https:\\\/\\\/manoli.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d0729c3168da9c3e36fb53f6012e0041\"},\"headline\":\"#MeToo : les femmes veulent se d\u00e9fendre &#8211; July 2018\",\"datePublished\":\"2018-12-29T18:39:31+00:00\",\"dateModified\":\"2019-09-10T22:24:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/manoli.ca\\\/metoo-les-femmes-veulent-se-defendre\\\/\"},\"wordCount\":1010,\"articleSection\":[\"Articles\",\"Assault prevention\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manoli.ca\\\/metoo-les-femmes-veulent-se-defendre\\\/\",\"url\":\"https:\\\/\\\/manoli.ca\\\/metoo-les-femmes-veulent-se-defendre\\\/\",\"name\":\"#MeToo : les femmes veulent se d\u00e9fendre - July 2018 - George Manoli Inc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manoli.ca\\\/fr\\\/#website\"},\"datePublished\":\"2018-12-29T18:39:31+00:00\",\"dateModified\":\"2019-09-10T22:24:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/manoli.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d0729c3168da9c3e36fb53f6012e0041\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manoli.ca\\\/metoo-les-femmes-veulent-se-defendre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manoli.ca\\\/metoo-les-femmes-veulent-se-defendre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manoli.ca\\\/metoo-les-femmes-veulent-se-defendre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/manoli.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#MeToo : les femmes veulent se d\u00e9fendre &#8211; July 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manoli.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/manoli.ca\\\/fr\\\/\",\"name\":\"George Manoli Inc\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manoli.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/manoli.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d0729c3168da9c3e36fb53f6012e0041\",\"name\":\"George Manoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfb7e16c5ce936855c764e57986c463dfe23263bc01d5806951de548bb6e2abd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfb7e16c5ce936855c764e57986c463dfe23263bc01d5806951de548bb6e2abd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfb7e16c5ce936855c764e57986c463dfe23263bc01d5806951de548bb6e2abd?s=96&d=mm&r=g\",\"caption\":\"George Manoli\"},\"sameAs\":[\"https:\\\/\\\/manoli.ca\\\/about-us\\\/the-director\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#MeToo : les femmes veulent se d\u00e9fendre - July 2018 - George Manoli Inc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/","og_locale":"fr_FR","og_type":"article","og_title":"#MeToo : les femmes veulent se d\u00e9fendre - July 2018 - George Manoli Inc","og_description":"This story was originally published in TVA Nouvelles (Video) Les femmes sont de plus en plus nombreuses \u00e0 s\u2019inscrire \u00e0 des cours d\u2019autod\u00e9fense \u00e0 Montr\u00e9al pour apprendre \u00e0 se prot\u00e9ger contre les agressions, moins d\u2019un an apr\u00e8s le mouvement #meToo. \u00ab Depuis le d\u00e9but de l\u2019ann\u00e9e, j\u2019ai doubl\u00e9, voire tripl\u00e9 le nombre de cours que ...","og_url":"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/","og_site_name":"George Manoli Inc","article_published_time":"2018-12-29T18:39:31+00:00","article_modified_time":"2019-09-10T22:24:47+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/manoli.ca\/wp-content\/uploads\/2015\/12\/Red-Barn-Logo-250-1.png","type":"image\/png"}],"author":"George Manoli","twitter_card":"summary_large_image","twitter_creator":"@tokondojo","twitter_site":"@tokondojo","twitter_misc":{"\u00c9crit par":"George Manoli","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/#article","isPartOf":{"@id":"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/"},"author":{"name":"George Manoli","@id":"https:\/\/manoli.ca\/fr\/#\/schema\/person\/d0729c3168da9c3e36fb53f6012e0041"},"headline":"#MeToo : les femmes veulent se d\u00e9fendre &#8211; July 2018","datePublished":"2018-12-29T18:39:31+00:00","dateModified":"2019-09-10T22:24:47+00:00","mainEntityOfPage":{"@id":"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/"},"wordCount":1010,"articleSection":["Articles","Assault prevention"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/","url":"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/","name":"#MeToo : les femmes veulent se d\u00e9fendre - July 2018 - George Manoli Inc","isPartOf":{"@id":"https:\/\/manoli.ca\/fr\/#website"},"datePublished":"2018-12-29T18:39:31+00:00","dateModified":"2019-09-10T22:24:47+00:00","author":{"@id":"https:\/\/manoli.ca\/fr\/#\/schema\/person\/d0729c3168da9c3e36fb53f6012e0041"},"breadcrumb":{"@id":"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/manoli.ca\/metoo-les-femmes-veulent-se-defendre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/manoli.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"#MeToo : les femmes veulent se d\u00e9fendre &#8211; July 2018"}]},{"@type":"WebSite","@id":"https:\/\/manoli.ca\/fr\/#website","url":"https:\/\/manoli.ca\/fr\/","name":"George Manoli Inc","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manoli.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/manoli.ca\/fr\/#\/schema\/person\/d0729c3168da9c3e36fb53f6012e0041","name":"George Manoli","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bfb7e16c5ce936855c764e57986c463dfe23263bc01d5806951de548bb6e2abd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bfb7e16c5ce936855c764e57986c463dfe23263bc01d5806951de548bb6e2abd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bfb7e16c5ce936855c764e57986c463dfe23263bc01d5806951de548bb6e2abd?s=96&d=mm&r=g","caption":"George Manoli"},"sameAs":["https:\/\/manoli.ca\/about-us\/the-director\/"]}]}},"_links":{"self":[{"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/posts\/5411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/comments?post=5411"}],"version-history":[{"count":3,"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/posts\/5411\/revisions"}],"predecessor-version":[{"id":5473,"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/posts\/5411\/revisions\/5473"}],"wp:attachment":[{"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/media?parent=5411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/categories?post=5411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manoli.ca\/fr\/wp-json\/wp\/v2\/tags?post=5411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}